{"id":308415,"date":"2026-04-03T11:38:24","date_gmt":"2026-04-03T09:38:24","guid":{"rendered":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-puzzle-mehrere-historische-segelschiffe-im-sonnenuntergang\/"},"modified":"2026-04-03T11:39:16","modified_gmt":"2026-04-03T09:39:16","slug":"raxxa-premium-puzzle-mehrere-historische-segelschiffe-im-sonnenuntergang","status":"publish","type":"product","link":"https:\/\/www.raxxa.com\/it\/shop\/raxxa-premium-puzzle-mehrere-historische-segelschiffe-im-sonnenuntergang\/","title":{"rendered":"raxxa Premium-Puzzle: Mehrere historische Segelschiffe im Sonnenuntergang"},"content":{"rendered":"<p><span style=\"font-family: helvetica, sans-serif;font-size: 24px\">puzzle fotografico premium raxxa<\/span><\/p>\n<div><span style=\"font-weight: bolder\">&#8222;Mehrere historische Segelschiffe im Sonnenuntergang&#8220; by Kerstin Waurick<\/span><\/div>\n<div><span style=\"font-weight: bolder\"><br \/><\/span><\/div>\n<div><span style=\"font-size: 1rem\">Dieses Bild zeigt stellvertretend f\u00fcr eine ganze Serie fotorealistischer, KI-generierter Darstellungen historischer Segelschiffe in ruhigen, gesch\u00fctzten Szenerien. Die Motive bewegen sich durch stille Buchten, gleiten durch dichten Nebel oder liegen vor den Silhouetten mittelalterlicher St\u00e4dte, in Momenten fern von Sturm und Eile. Licht und Atmosph\u00e4re tragen eine leise, fast zeitenthobene Stimmung, w\u00e4hrend die detailreiche Ausarbeitung von Schiff, Wasser und Architektur eine Welt entstehen l\u00e4sst, die zugleich vergangen und gegenw\u00e4rtig wirkt.<\/span><\/div>\n<div><\/div>\n<p><\/p>\n<div>\n<ul class=\"list-normal\" style=\"margin-right: 0px;margin-left: 0px;padding: 0px 0px 0px 1rem;border: 0px;line-height: 26px\">\n<li style=\"font-family: Lato_Light, sans-serif;font-size: 14.4px;margin: 0px;padding: 0px;border: 0px\">1000 pezzi = L 68 x H 48 cm, pezzi del puzzle circa 1,9 x 1,6 cm.<\/li>\n<li style=\"font-family: Lato_Light, sans-serif;font-size: 14.4px;margin: 0px;padding: 0px;border: 0px\">Tavola puzzle premium blu con spessore di 1,9 mm. I pezzi del puzzle si incastrano perfettamente.<\/li>\n<li style=\"font-family: Lato_Light, sans-serif;font-size: 14.4px;margin: 0px;padding: 0px;border: 0px\">Massima qualit\u00e0 di stampa HD per gradazioni di colore sottili e colori brillanti su cartoncino di alta qualit\u00e0 per una rappresentazione ottimale dei dettagli.<\/li>\n<li style=\"font-family: Lato_Light, sans-serif;font-size: 14.4px;margin: 0px;padding: 0px;border: 0px\">Scatola con coperchio a scorrimento, carta di lino finemente goffrata con vernice protettiva a base d'acqua per una migliore durata della scatola.<\/li>\n<li style=\"font-family: Lato_Light, sans-serif;font-size: 14.4px;margin: 0px;padding: 0px;border: 0px\">Produzione completamente neutrale dal punto di vista climatico, FSC<\/li>\n<li style=\"font-family: Lato_Light, sans-serif;font-size: 14.4px;margin: 0px;padding: 0px;border: 0px\">Prodotto in Germania<\/li>\n<\/ul>\n<p><\/p>\n<p style=\"margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding: 0px;border: 0px\"><\/p>\n<p style=\"margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding: 0px;border: 0px\"><span style=\"font-size: 1rem\">Un vero pezzo unico. Il motivo desiderato sar\u00e0 prodotto e spedito appositamente per voi solo dopo aver ricevuto l'ordine.<\/span><\/p>\n<p style=\"margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding: 0px;border: 0px\"><span style=\"font-size: 1rem\">Attenzione: pericolo di soffocamento a causa delle piccole parti che possono essere ingerite.<\/span><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>raxxa Premium-Fotopuzzle &#8222;Mehrere historische Segelschiffe im Sonnenuntergang&#8220; by Kerstin Waurick Dieses Bild zeigt stellvertretend f\u00fcr eine ganze Serie fotorealistischer, KI-generierter Darstellungen historischer Segelschiffe in ruhigen, gesch\u00fctzten Szenerien. Die Motive bewegen sich durch stille Buchten, gleiten durch dichten Nebel oder liegen vor den Silhouetten mittelalterlicher St\u00e4dte, in Momenten fern von Sturm und Eile. Licht und Atmosph\u00e4re [&hellip;]<\/p>\n","protected":false},"featured_media":308416,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[159,10365,13429],"product_tag":[],"class_list":["post-308415","product","type-product","status-publish","has-post-thumbnail","product_cat-fahrzeuge","product_cat-puzzle","product_cat-kerstin-waurick","product_shipping_class-versand-puzzle","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>raxxa Premium-Puzzle: Mehrere historische Segelschiffe im Sonnenuntergang - raxxa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.raxxa.com\/it\/shop\/raxxa-premium-puzzle-mehrere-historische-segelschiffe-im-sonnenuntergang\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"raxxa Premium-Puzzle: Mehrere historische Segelschiffe im Sonnenuntergang\" \/>\n<meta property=\"og:description\" content=\"raxxa Premium-Fotopuzzle &#8222;Mehrere historische Segelschiffe im Sonnenuntergang&#8220; by Kerstin Waurick Dieses Bild zeigt stellvertretend f\u00fcr eine ganze Serie fotorealistischer, KI-generierter Darstellungen historischer Segelschiffe in ruhigen, gesch\u00fctzten Szenerien. Die Motive bewegen sich durch stille Buchten, gleiten durch dichten Nebel oder liegen vor den Silhouetten mittelalterlicher St\u00e4dte, in Momenten fern von Sturm und Eile. Licht und Atmosph\u00e4re [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.raxxa.com\/it\/shop\/raxxa-premium-puzzle-mehrere-historische-segelschiffe-im-sonnenuntergang\/\" \/>\n<meta property=\"og:site_name\" content=\"raxxa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/raxxacom\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-03T09:39:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prezzo\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;29,99\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e0\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-puzzle-mehrere-historische-segelschiffe-im-sonnenuntergang\\\/\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-puzzle-mehrere-historische-segelschiffe-im-sonnenuntergang\\\/\",\"name\":\"raxxa Premium-Puzzle: Mehrere historische Segelschiffe im Sonnenuntergang - raxxa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-puzzle-mehrere-historische-segelschiffe-im-sonnenuntergang\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-puzzle-mehrere-historische-segelschiffe-im-sonnenuntergang\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/raxxa-puzzle-373-24669-Kerstin-Waurick-Mehrere-historische-Segelschiffe-im-Sonnenuntergang-box.png\",\"datePublished\":\"2026-04-03T09:38:24+00:00\",\"dateModified\":\"2026-04-03T09:39:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-puzzle-mehrere-historische-segelschiffe-im-sonnenuntergang\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-puzzle-mehrere-historische-segelschiffe-im-sonnenuntergang\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-puzzle-mehrere-historische-segelschiffe-im-sonnenuntergang\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/raxxa-puzzle-373-24669-Kerstin-Waurick-Mehrere-historische-Segelschiffe-im-Sonnenuntergang-box.png\",\"contentUrl\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/raxxa-puzzle-373-24669-Kerstin-Waurick-Mehrere-historische-Segelschiffe-im-Sonnenuntergang-box.png\",\"width\":1920,\"height\":1400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-puzzle-mehrere-historische-segelschiffe-im-sonnenuntergang\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.raxxa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.raxxa.com\\\/it\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"raxxa Premium-Puzzle: Mehrere historische Segelschiffe im Sonnenuntergang\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#website\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/\",\"name\":\"raxxa\",\"description\":\"Einzigartige individuelle Produkte von unseren Designern\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.raxxa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#organization\",\"name\":\"raxxa\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo_v2.png\",\"contentUrl\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo_v2.png\",\"width\":380,\"height\":382,\"caption\":\"raxxa\"},\"image\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/raxxacom\"]}]}<\/script>\n<meta property=\"product:price:amount\" content=\"29.99\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"1-14270-24669-373\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"raxxa Premium-Puzzle: Mehrere historische Segelschiffe im Sonnenuntergang - raxxa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.raxxa.com\/it\/shop\/raxxa-premium-puzzle-mehrere-historische-segelschiffe-im-sonnenuntergang\/","og_locale":"it_IT","og_type":"article","og_title":"raxxa Premium-Puzzle: Mehrere historische Segelschiffe im Sonnenuntergang","og_description":"raxxa Premium-Fotopuzzle &#8222;Mehrere historische Segelschiffe im Sonnenuntergang&#8220; by Kerstin Waurick Dieses Bild zeigt stellvertretend f\u00fcr eine ganze Serie fotorealistischer, KI-generierter Darstellungen historischer Segelschiffe in ruhigen, gesch\u00fctzten Szenerien. Die Motive bewegen sich durch stille Buchten, gleiten durch dichten Nebel oder liegen vor den Silhouetten mittelalterlicher St\u00e4dte, in Momenten fern von Sturm und Eile. Licht und Atmosph\u00e4re [&hellip;]","og_url":"https:\/\/www.raxxa.com\/it\/shop\/raxxa-premium-puzzle-mehrere-historische-segelschiffe-im-sonnenuntergang\/","og_site_name":"raxxa","article_publisher":"https:\/\/facebook.com\/raxxacom","article_modified_time":"2026-04-03T09:39:16+00:00","twitter_card":"summary_large_image","twitter_misc":{"Prezzo":"&euro;29,99","Disponibilit\u00e0":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-puzzle-mehrere-historische-segelschiffe-im-sonnenuntergang\/","url":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-puzzle-mehrere-historische-segelschiffe-im-sonnenuntergang\/","name":"raxxa Premium-Puzzle: Mehrere historische Segelschiffe im Sonnenuntergang - raxxa","isPartOf":{"@id":"https:\/\/www.raxxa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-puzzle-mehrere-historische-segelschiffe-im-sonnenuntergang\/#primaryimage"},"image":{"@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-puzzle-mehrere-historische-segelschiffe-im-sonnenuntergang\/#primaryimage"},"thumbnailUrl":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2026\/04\/raxxa-puzzle-373-24669-Kerstin-Waurick-Mehrere-historische-Segelschiffe-im-Sonnenuntergang-box.png","datePublished":"2026-04-03T09:38:24+00:00","dateModified":"2026-04-03T09:39:16+00:00","breadcrumb":{"@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-puzzle-mehrere-historische-segelschiffe-im-sonnenuntergang\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.raxxa.com\/shop\/raxxa-premium-puzzle-mehrere-historische-segelschiffe-im-sonnenuntergang\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-puzzle-mehrere-historische-segelschiffe-im-sonnenuntergang\/#primaryimage","url":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2026\/04\/raxxa-puzzle-373-24669-Kerstin-Waurick-Mehrere-historische-Segelschiffe-im-Sonnenuntergang-box.png","contentUrl":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2026\/04\/raxxa-puzzle-373-24669-Kerstin-Waurick-Mehrere-historische-Segelschiffe-im-Sonnenuntergang-box.png","width":1920,"height":1400},{"@type":"BreadcrumbList","@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-puzzle-mehrere-historische-segelschiffe-im-sonnenuntergang\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.raxxa.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.raxxa.com\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"raxxa Premium-Puzzle: Mehrere historische Segelschiffe im Sonnenuntergang"}]},{"@type":"WebSite","@id":"https:\/\/www.raxxa.com\/#website","url":"https:\/\/www.raxxa.com\/","name":"raxxa","description":"Prodotti unici e personalizzati dei nostri designer","publisher":{"@id":"https:\/\/www.raxxa.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.raxxa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.raxxa.com\/#organization","name":"raxxa","url":"https:\/\/www.raxxa.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.raxxa.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2022\/07\/logo_v2.png","contentUrl":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2022\/07\/logo_v2.png","width":380,"height":382,"caption":"raxxa"},"image":{"@id":"https:\/\/www.raxxa.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/raxxacom"]}]},"product_price_amount":"29.99","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"1-14270-24669-373","product_condition":"new"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.raxxa.com\/it\/wp-json\/wp\/v2\/product\/308415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.raxxa.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.raxxa.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.raxxa.com\/it\/wp-json\/wp\/v2\/comments?post=308415"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.raxxa.com\/it\/wp-json\/wp\/v2\/media\/308416"}],"wp:attachment":[{"href":"https:\/\/www.raxxa.com\/it\/wp-json\/wp\/v2\/media?parent=308415"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.raxxa.com\/it\/wp-json\/wp\/v2\/product_brand?post=308415"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.raxxa.com\/it\/wp-json\/wp\/v2\/product_cat?post=308415"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.raxxa.com\/it\/wp-json\/wp\/v2\/product_tag?post=308415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}