{"id":206563,"date":"2024-10-03T00:03:16","date_gmt":"2024-10-02T22:03:16","guid":{"rendered":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-puzzle-la-salida-del-sol\/"},"modified":"2025-11-03T06:31:32","modified_gmt":"2025-11-03T04:31:32","slug":"raxxa-premium-puzzle-la-salida-del-sol","status":"publish","type":"product","link":"https:\/\/www.raxxa.com\/it\/shop\/raxxa-premium-puzzle-la-salida-del-sol\/","title":{"rendered":"puzzle premium di raxxa: La salida del sol"},"content":{"rendered":"<p><span style=\"color: rgb(0, 0, 0); font-family: helvetica, sans-serif; font-size: 24px;\">puzzle fotografico premium raxxa<\/span><\/p>\n<div><span style=\"font-weight: bolder;color: rgb(0, 0, 0);\">&#8222;La salida del sol&#8220; by Nuria Art<\/span><\/div>\n<div><span style=\"font-weight: bolder;\"><br \/><\/span><\/div>\n<div><span style=\"font-size: 1rem;color: rgb(0, 0, 0);\">Il Natale del giorno, accompagnato dal sole che ci d\u00e0 energia e allegria. Un'opera che offre un tributo agli amanti del giorno. L'intenzione dell'artista \u00e8 quella di creare momenti di ricordo di questi amori spettacolari, tranquilli e sereni.<\/span><\/div>\n<div><\/div>\n<p><\/p>\n<div>\n<ul class=\"list-normal\" style=\"margin-right: 0px; margin-left: 0px; padding: 0px 0px 0px 1rem; border: 0px; text-size-adjust: none; list-style: inside none square; line-height: 26px;\">\n<li style=\"color: rgb(51, 51, 51); font-family: Lato_Light, sans-serif; font-size: 14.4px; margin: 0px; padding: 0px; border: 0px; text-size-adjust: none;\">1000 pezzi = L 68 x H 48 cm, pezzi del puzzle circa 1,9 x 1,6 cm.<\/li>\n<li style=\"color: rgb(51, 51, 51); font-family: Lato_Light, sans-serif; font-size: 14.4px; margin: 0px; padding: 0px; border: 0px; text-size-adjust: none;\">Tavola puzzle premium blu con spessore di 1,9 mm. I pezzi del puzzle si incastrano perfettamente.<\/li>\n<li style=\"color: rgb(51, 51, 51); font-family: Lato_Light, sans-serif; font-size: 14.4px; margin: 0px; padding: 0px; border: 0px; text-size-adjust: none;\">Massima qualit\u00e0 di stampa HD per gradazioni di colore sottili e colori brillanti su cartoncino di alta qualit\u00e0 per una rappresentazione ottimale dei dettagli.<\/li>\n<li style=\"color: rgb(51, 51, 51); font-family: Lato_Light, sans-serif; font-size: 14.4px; margin: 0px; padding: 0px; border: 0px; text-size-adjust: none;\">Scatola con coperchio a scorrimento, carta di lino finemente goffrata con vernice protettiva a base d'acqua per una migliore durata della scatola.<\/li>\n<li style=\"color: rgb(51, 51, 51); font-family: Lato_Light, sans-serif; font-size: 14.4px; margin: 0px; padding: 0px; border: 0px; text-size-adjust: none;\">Produzione completamente neutrale dal punto di vista climatico, FSC<\/li>\n<li style=\"color: rgb(51, 51, 51); font-family: Lato_Light, sans-serif; font-size: 14.4px; margin: 0px; padding: 0px; border: 0px; text-size-adjust: none;\">Prodotto in Germania<\/li>\n<\/ul>\n<p><\/p>\n<p style=\"margin-right: 0px; margin-bottom: 0px; margin-left: 0px; padding: 0px; border: 0px; text-size-adjust: none;\"><\/p>\n<p style=\"margin-right: 0px; margin-bottom: 0px; margin-left: 0px; padding: 0px; border: 0px; text-size-adjust: none;\"><span style=\"font-size: 1rem;\">Un vero pezzo unico. Il motivo desiderato sar\u00e0 prodotto e spedito appositamente per voi solo dopo aver ricevuto l'ordine.<\/span><\/p>\n<p style=\"margin-right: 0px; margin-bottom: 0px; margin-left: 0px; padding: 0px; border: 0px; text-size-adjust: none;\"><span style=\"font-size: 1rem;\">Attenzione: pericolo di soffocamento a causa delle piccole parti che possono essere ingerite.<\/span><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>raxxa Premium-Fotopuzzle &#8222;La salida del sol&#8220; by Nuria Art El nacimiento del d\u00eda, acompa\u00f1ado del sol que nos da energ\u00eda y alegr\u00eda. Una obra que rinda un atributo a los amaneceres diarios. La intenci\u00f3n de la artista es crear momentos de recuerdos de esos amaneceres espectaculares, tranquilos y en calma. 1000 Teile = B 68 [&hellip;]<\/p>\n","protected":false},"featured_media":253097,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[137,12508,10365],"product_tag":[],"class_list":{"0":"post-206563","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-abstrakt","7":"product_cat-nuria-art","8":"product_cat-puzzle","9":"product_shipping_class-versand-puzzle","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>raxxa Premium-Puzzle: La salida del sol - raxxa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.raxxa.com\/it\/shop\/raxxa-premium-puzzle-la-salida-del-sol\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"raxxa Premium-Puzzle: La salida del sol\" \/>\n<meta property=\"og:description\" content=\"raxxa Premium-Fotopuzzle &#8222;La salida del sol&#8220; by Nuria Art El nacimiento del d\u00eda, acompa\u00f1ado del sol que nos da energ\u00eda y alegr\u00eda. Una obra que rinda un atributo a los amaneceres diarios. La intenci\u00f3n de la artista es crear momentos de recuerdos de esos amaneceres espectaculares, tranquilos y en calma. 1000 Teile = B 68 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.raxxa.com\/it\/shop\/raxxa-premium-puzzle-la-salida-del-sol\/\" \/>\n<meta property=\"og:site_name\" content=\"raxxa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/raxxacom\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-03T04:31:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.raxxa.com\/wp-content\/uploads\/2024\/10\/raxxa-puzzle-324-17832-Nuria-Art-La-salida-del-sol-box.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prezzo\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;29,99\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e0\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-puzzle-la-salida-del-sol\\\/\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-puzzle-la-salida-del-sol\\\/\",\"name\":\"raxxa Premium-Puzzle: La salida del sol - raxxa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-puzzle-la-salida-del-sol\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-puzzle-la-salida-del-sol\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/raxxa-puzzle-324-17832-Nuria-Art-La-salida-del-sol-box.png\",\"datePublished\":\"2024-10-02T22:03:16+00:00\",\"dateModified\":\"2025-11-03T04:31:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-puzzle-la-salida-del-sol\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-puzzle-la-salida-del-sol\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-puzzle-la-salida-del-sol\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/raxxa-puzzle-324-17832-Nuria-Art-La-salida-del-sol-box.png\",\"contentUrl\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/raxxa-puzzle-324-17832-Nuria-Art-La-salida-del-sol-box.png\",\"width\":2400,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-puzzle-la-salida-del-sol\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.raxxa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.raxxa.com\\\/it\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"raxxa Premium-Puzzle: La salida del sol\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#website\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/\",\"name\":\"raxxa\",\"description\":\"Einzigartige individuelle Produkte von unseren Designern\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.raxxa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#organization\",\"name\":\"raxxa\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo_v2.png\",\"contentUrl\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo_v2.png\",\"width\":380,\"height\":382,\"caption\":\"raxxa\"},\"image\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/raxxacom\"]}]}<\/script>\n<meta property=\"product:price:amount\" content=\"29.99\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"1-14270-17832-324\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"raxxa Premium-Puzzle: La salida del sol - raxxa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.raxxa.com\/it\/shop\/raxxa-premium-puzzle-la-salida-del-sol\/","og_locale":"it_IT","og_type":"article","og_title":"raxxa Premium-Puzzle: La salida del sol","og_description":"raxxa Premium-Fotopuzzle &#8222;La salida del sol&#8220; by Nuria Art El nacimiento del d\u00eda, acompa\u00f1ado del sol que nos da energ\u00eda y alegr\u00eda. Una obra que rinda un atributo a los amaneceres diarios. La intenci\u00f3n de la artista es crear momentos de recuerdos de esos amaneceres espectaculares, tranquilos y en calma. 1000 Teile = B 68 [&hellip;]","og_url":"https:\/\/www.raxxa.com\/it\/shop\/raxxa-premium-puzzle-la-salida-del-sol\/","og_site_name":"raxxa","article_publisher":"https:\/\/facebook.com\/raxxacom","article_modified_time":"2025-11-03T04:31:32+00:00","og_image":[{"width":2400,"height":1600,"url":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2024\/10\/raxxa-puzzle-324-17832-Nuria-Art-La-salida-del-sol-box.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Prezzo":"&euro;29,99","Disponibilit\u00e0":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-puzzle-la-salida-del-sol\/","url":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-puzzle-la-salida-del-sol\/","name":"raxxa Premium-Puzzle: La salida del sol - raxxa","isPartOf":{"@id":"https:\/\/www.raxxa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-puzzle-la-salida-del-sol\/#primaryimage"},"image":{"@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-puzzle-la-salida-del-sol\/#primaryimage"},"thumbnailUrl":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2024\/10\/raxxa-puzzle-324-17832-Nuria-Art-La-salida-del-sol-box.png","datePublished":"2024-10-02T22:03:16+00:00","dateModified":"2025-11-03T04:31:32+00:00","breadcrumb":{"@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-puzzle-la-salida-del-sol\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.raxxa.com\/shop\/raxxa-premium-puzzle-la-salida-del-sol\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-puzzle-la-salida-del-sol\/#primaryimage","url":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2024\/10\/raxxa-puzzle-324-17832-Nuria-Art-La-salida-del-sol-box.png","contentUrl":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2024\/10\/raxxa-puzzle-324-17832-Nuria-Art-La-salida-del-sol-box.png","width":2400,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-puzzle-la-salida-del-sol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.raxxa.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.raxxa.com\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"raxxa Premium-Puzzle: La salida del sol"}]},{"@type":"WebSite","@id":"https:\/\/www.raxxa.com\/#website","url":"https:\/\/www.raxxa.com\/","name":"raxxa","description":"Prodotti unici e personalizzati dei nostri designer","publisher":{"@id":"https:\/\/www.raxxa.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.raxxa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.raxxa.com\/#organization","name":"raxxa","url":"https:\/\/www.raxxa.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.raxxa.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2022\/07\/logo_v2.png","contentUrl":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2022\/07\/logo_v2.png","width":380,"height":382,"caption":"raxxa"},"image":{"@id":"https:\/\/www.raxxa.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/raxxacom"]}]},"product_price_amount":"29.99","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"1-14270-17832-324","product_condition":"new"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.raxxa.com\/it\/wp-json\/wp\/v2\/product\/206563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.raxxa.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.raxxa.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.raxxa.com\/it\/wp-json\/wp\/v2\/comments?post=206563"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.raxxa.com\/it\/wp-json\/wp\/v2\/media\/253097"}],"wp:attachment":[{"href":"https:\/\/www.raxxa.com\/it\/wp-json\/wp\/v2\/media?parent=206563"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.raxxa.com\/it\/wp-json\/wp\/v2\/product_brand?post=206563"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.raxxa.com\/it\/wp-json\/wp\/v2\/product_cat?post=206563"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.raxxa.com\/it\/wp-json\/wp\/v2\/product_tag?post=206563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}