{"id":303400,"date":"2026-03-24T23:04:28","date_gmt":"2026-03-24T21:04:28","guid":{"rendered":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-tasse-gruppenbild-mit-neugierigen-kaninchen\/"},"modified":"2026-03-24T23:04:54","modified_gmt":"2026-03-24T21:04:54","slug":"raxxa-premium-tasse-gruppenbild-mit-neugierigen-kaninchen","status":"publish","type":"product","link":"https:\/\/www.raxxa.com\/fr\/shop\/raxxa-premium-tasse-gruppenbild-mit-neugierigen-kaninchen\/","title":{"rendered":"raxxa Premium-Tasse: Gruppenbild mit neugierigen Kaninchen"},"content":{"rendered":"<h3><strong>&quot;Gruppenbild mit neugierigen Kaninchen&quot; by Kerstin Waurick<\/strong><\/h3>\n<p><strong><\/strong><\/p>\n<p>Dieses charmante Bild zeigt Kaninchen als dichte, lebendige Ansammlung neugieriger Tiere, die sich eng aneinander dr\u00e4ngen und gemeinsam das gesamte Bild f\u00fcllen. Alle Blicke sind auf den Betrachter gerichtet, wodurch eine direkte, fast spielerische Verbindung entsteht. Weiche Formen und flauschige Strukturen verleihen der Szene eine warme, fr\u00f6hliche Ausstrahlung, ohne ins Kitschige zu kippen. Mithilfe moderner KI entsteht so eine detailreiche Komposition voller Leben, N\u00e4he und stiller Heiterkeit.<\/p>\n<p>&nbsp;<\/p>\n<ul><li>DIMENSIONEN: Mit Ma\u00dfen von H\u00f6he: 95 mm, \u00d8 80 mm und einer Kapazit\u00e4t von ca. 330ml ist sie die ideale Wahl f\u00fcr jeden Kaffeeliebhaber oder Teetrinker.<\/li><li>LANGLEBIG: Diese weisse Keramik-Tasse ist sowohl sp\u00fclmaschinen- als auch mikrowellenfest.<\/li><li>SPEZIELL: Jedes St\u00fcck ist ein ganz besonderes individuelles Produkt und wird erst nach der Bestellung extra f\u00fcr Sie mit Ihrem Wunschmotiv angefertigt.<\/li><li>ECHTES HANDWERK: Die Tassen werden mit Sorgfalt in Deutschland bedruckt, garantieren Langlebigkeit der Designs und sind das perfekte Geschenk.<\/li><li>UNTERST\u00dcTZUNG: Mit Ihrem Kauf eines raxxa-Produkts wird direkt ein K\u00fcnstler aus unserer raxxa-Community von aktuell \u00fcber 200 K\u00fcnstlern \/ Designern \/ Fotografen unterst\u00fctzt.<\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>&quot;Gruppenbild mit neugierigen Kaninchen&quot; by Kerstin Waurick Dieses charmante Bild zeigt Kaninchen als dichte, lebendige Ansammlung neugieriger Tiere, die sich eng aneinander dr\u00e4ngen und gemeinsam das gesamte Bild f\u00fcllen. Alle Blicke sind auf den Betrachter gerichtet, wodurch eine direkte, fast spielerische Verbindung entsteht. Weiche Formen und flauschige Strukturen verleihen der Szene eine warme, fr\u00f6hliche Ausstrahlung, [&hellip;]<\/p>\n","protected":false},"featured_media":303402,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[11606,133,13429],"product_tag":[],"class_list":["post-303400","product","type-product","status-publish","has-post-thumbnail","product_cat-tassen","product_cat-tiere","product_cat-kerstin-waurick","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>raxxa Premium-Tasse: Gruppenbild mit neugierigen Kaninchen - raxxa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.raxxa.com\/fr\/shop\/raxxa-premium-tasse-gruppenbild-mit-neugierigen-kaninchen\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"raxxa Premium-Tasse: Gruppenbild mit neugierigen Kaninchen\" \/>\n<meta property=\"og:description\" content=\"&quot;Gruppenbild mit neugierigen Kaninchen&quot; by Kerstin Waurick Dieses charmante Bild zeigt Kaninchen als dichte, lebendige Ansammlung neugieriger Tiere, die sich eng aneinander dr\u00e4ngen und gemeinsam das gesamte Bild f\u00fcllen. Alle Blicke sind auf den Betrachter gerichtet, wodurch eine direkte, fast spielerische Verbindung entsteht. Weiche Formen und flauschige Strukturen verleihen der Szene eine warme, fr\u00f6hliche Ausstrahlung, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.raxxa.com\/fr\/shop\/raxxa-premium-tasse-gruppenbild-mit-neugierigen-kaninchen\/\" \/>\n<meta property=\"og:site_name\" content=\"raxxa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/raxxacom\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-24T21:04:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;14,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-tasse-gruppenbild-mit-neugierigen-kaninchen\\\/\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-tasse-gruppenbild-mit-neugierigen-kaninchen\\\/\",\"name\":\"raxxa Premium-Tasse: Gruppenbild mit neugierigen Kaninchen - raxxa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-tasse-gruppenbild-mit-neugierigen-kaninchen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-tasse-gruppenbild-mit-neugierigen-kaninchen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/raxxa-Tasse-373-24346-143-Kerstin-Waurick-Gruppenbild-mit-neugierigen-Kaninchen-1-scaled.jpg\",\"datePublished\":\"2026-03-24T21:04:28+00:00\",\"dateModified\":\"2026-03-24T21:04:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-tasse-gruppenbild-mit-neugierigen-kaninchen\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-tasse-gruppenbild-mit-neugierigen-kaninchen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-tasse-gruppenbild-mit-neugierigen-kaninchen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/raxxa-Tasse-373-24346-143-Kerstin-Waurick-Gruppenbild-mit-neugierigen-Kaninchen-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/raxxa-Tasse-373-24346-143-Kerstin-Waurick-Gruppenbild-mit-neugierigen-Kaninchen-1-scaled.jpg\",\"width\":2560,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-tasse-gruppenbild-mit-neugierigen-kaninchen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.raxxa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.raxxa.com\\\/it\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"raxxa Premium-Tasse: Gruppenbild mit neugierigen Kaninchen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#website\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/\",\"name\":\"raxxa\",\"description\":\"Einzigartige individuelle Produkte von unseren Designern\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.raxxa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#organization\",\"name\":\"raxxa\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo_v2.png\",\"contentUrl\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo_v2.png\",\"width\":380,\"height\":382,\"caption\":\"raxxa\"},\"image\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/raxxacom\"]}]}<\/script>\n<meta property=\"product:price:amount\" content=\"14.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"1-14518-24346-373\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"raxxa Premium-Tasse: Gruppenbild mit neugierigen Kaninchen - raxxa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.raxxa.com\/fr\/shop\/raxxa-premium-tasse-gruppenbild-mit-neugierigen-kaninchen\/","og_locale":"fr_FR","og_type":"article","og_title":"raxxa Premium-Tasse: Gruppenbild mit neugierigen Kaninchen","og_description":"&quot;Gruppenbild mit neugierigen Kaninchen&quot; by Kerstin Waurick Dieses charmante Bild zeigt Kaninchen als dichte, lebendige Ansammlung neugieriger Tiere, die sich eng aneinander dr\u00e4ngen und gemeinsam das gesamte Bild f\u00fcllen. Alle Blicke sind auf den Betrachter gerichtet, wodurch eine direkte, fast spielerische Verbindung entsteht. Weiche Formen und flauschige Strukturen verleihen der Szene eine warme, fr\u00f6hliche Ausstrahlung, [&hellip;]","og_url":"https:\/\/www.raxxa.com\/fr\/shop\/raxxa-premium-tasse-gruppenbild-mit-neugierigen-kaninchen\/","og_site_name":"raxxa","article_publisher":"https:\/\/facebook.com\/raxxacom","article_modified_time":"2026-03-24T21:04:54+00:00","twitter_card":"summary_large_image","twitter_misc":{"Prix":"&euro;14,90","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-tasse-gruppenbild-mit-neugierigen-kaninchen\/","url":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-tasse-gruppenbild-mit-neugierigen-kaninchen\/","name":"raxxa Premium-Tasse: Gruppenbild mit neugierigen Kaninchen - raxxa","isPartOf":{"@id":"https:\/\/www.raxxa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-tasse-gruppenbild-mit-neugierigen-kaninchen\/#primaryimage"},"image":{"@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-tasse-gruppenbild-mit-neugierigen-kaninchen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2026\/03\/raxxa-Tasse-373-24346-143-Kerstin-Waurick-Gruppenbild-mit-neugierigen-Kaninchen-1-scaled.jpg","datePublished":"2026-03-24T21:04:28+00:00","dateModified":"2026-03-24T21:04:54+00:00","breadcrumb":{"@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-tasse-gruppenbild-mit-neugierigen-kaninchen\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.raxxa.com\/shop\/raxxa-premium-tasse-gruppenbild-mit-neugierigen-kaninchen\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-tasse-gruppenbild-mit-neugierigen-kaninchen\/#primaryimage","url":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2026\/03\/raxxa-Tasse-373-24346-143-Kerstin-Waurick-Gruppenbild-mit-neugierigen-Kaninchen-1-scaled.jpg","contentUrl":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2026\/03\/raxxa-Tasse-373-24346-143-Kerstin-Waurick-Gruppenbild-mit-neugierigen-Kaninchen-1-scaled.jpg","width":2560,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-tasse-gruppenbild-mit-neugierigen-kaninchen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.raxxa.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.raxxa.com\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"raxxa Premium-Tasse: Gruppenbild mit neugierigen Kaninchen"}]},{"@type":"WebSite","@id":"https:\/\/www.raxxa.com\/#website","url":"https:\/\/www.raxxa.com\/","name":"raxxa","description":"Des produits uniques et personnalis\u00e9s cr\u00e9\u00e9s par nos designers","publisher":{"@id":"https:\/\/www.raxxa.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.raxxa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.raxxa.com\/#organization","name":"raxxa","url":"https:\/\/www.raxxa.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.raxxa.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2022\/07\/logo_v2.png","contentUrl":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2022\/07\/logo_v2.png","width":380,"height":382,"caption":"raxxa"},"image":{"@id":"https:\/\/www.raxxa.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/raxxacom"]}]},"product_price_amount":"14.90","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"1-14518-24346-373","product_condition":"new"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.raxxa.com\/fr\/wp-json\/wp\/v2\/product\/303400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.raxxa.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.raxxa.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.raxxa.com\/fr\/wp-json\/wp\/v2\/comments?post=303400"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.raxxa.com\/fr\/wp-json\/wp\/v2\/media\/303402"}],"wp:attachment":[{"href":"https:\/\/www.raxxa.com\/fr\/wp-json\/wp\/v2\/media?parent=303400"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.raxxa.com\/fr\/wp-json\/wp\/v2\/product_brand?post=303400"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.raxxa.com\/fr\/wp-json\/wp\/v2\/product_cat?post=303400"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.raxxa.com\/fr\/wp-json\/wp\/v2\/product_tag?post=303400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}