{"id":289159,"date":"2026-03-01T18:56:34","date_gmt":"2026-03-01T16:56:34","guid":{"rendered":"https:\/\/www.raxxa.com\/shop\/raxxa-postkarte-suesses-baby-koala\/"},"modified":"2026-03-01T18:57:53","modified_gmt":"2026-03-01T16:57:53","slug":"raxxa-postkarte-suesses-baby-koala","status":"publish","type":"product","link":"https:\/\/www.raxxa.com\/fr\/shop\/raxxa-postkarte-suesses-baby-koala\/","title":{"rendered":"raxxa Postkarte: S\u00fc\u00dfes Baby-Koala"},"content":{"rendered":"<h3><strong>&quot;S\u00fc\u00dfes Baby-Koala&quot; by Slothy<\/strong><\/h3>\n<p><strong><\/strong><\/p>\n<p>Dieses Baby-Koala schmilzt Herzen im ersten Moment. Flauschiges Fell, riesige Kulleraugen und ein fr\u00f6hliches L\u00e4cheln machen es absolut unwiderstehlich. Perfekt als Geschenk, Deko oder Sammlerst\u00fcck \u2013 einmal gesehen, sofort verliebt.<\/p>\n<p>&nbsp;<\/p>\n<ul><li>Nous imprimons la carte postale de votre choix en blanc ou avec un message personnel et l'envoyons dans le monde entier \u00e0 la personne de votre choix ou \u00e0 vous-m\u00eame.<\/li><li>Id\u00e9al pour le Postcrossing en ligne ou les v\u0153ux personnalis\u00e9s \u00e0 vos proches, vos amis, vos parents et vos connaissances.<\/li><li>Alternativement, en tant que carte vierge \u00e0 motif pur \u00e0 collectionner ou \u00e0 envoyer soi-m\u00eame.<\/li><li>Cartes postales DIN A6 (14,8 cm x 10,5 cm).<\/li><\/ul><br><br><b>Comment cr\u00e9er\/concevoir ma carte postale personnelle ?<\/b><br><br>1) Saisissez simplement le texte de votre message ou de votre salut (500 caract\u00e8res maximum).<br>2) Si vous souhaitez envoyer votre carte postale pour Postcrossing, inscrivez le PostcrossingID.<br>Sinon, laissez simplement ce champ vide.<br>3) Saisissez le pr\u00e9nom, le nom, le num\u00e9ro de rue, le code postal, la ville et le pays du destinataire de la carte postale dans les champs de saisie.<br>4) Vous pouvez maintenant ajouter votre carte postale personnalis\u00e9e au panier et la commander \u00e0 la caisse.<br><br>Nous imprimons maintenant votre carte postale personnelle, l'affranchissons et l'envoyons au destinataire que vous avez indiqu\u00e9.<br><br>Si vous avez des questions, n'h\u00e9sitez pas \u00e0 nous envoyer un message ou un e-mail.<br>","protected":false},"excerpt":{"rendered":"<p>&quot;S\u00fc\u00dfes Baby-Koala&quot; by Slothy Dieses Baby-Koala schmilzt Herzen im ersten Moment. Flauschiges Fell, riesige Kulleraugen und ein fr\u00f6hliches L\u00e4cheln machen es absolut unwiderstehlich. Perfekt als Geschenk, Deko oder Sammlerst\u00fcck \u2013 einmal gesehen, sofort verliebt. &nbsp;<\/p>","protected":false},"featured_media":289160,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[11041,11884,10765],"product_tag":[],"class_list":["post-289159","product","type-product","status-publish","has-post-thumbnail","product_cat-digital","product_cat-postkarten","product_cat-slothy","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>raxxa Postkarte: S\u00fc\u00dfes Baby-Koala - raxxa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.raxxa.com\/fr\/shop\/raxxa-postkarte-suesses-baby-koala\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"raxxa Postkarte: S\u00fc\u00dfes Baby-Koala\" \/>\n<meta property=\"og:description\" content=\"&quot;S\u00fc\u00dfes Baby-Koala&quot; by Slothy Dieses Baby-Koala schmilzt Herzen im ersten Moment. Flauschiges Fell, riesige Kulleraugen und ein fr\u00f6hliches L\u00e4cheln machen es absolut unwiderstehlich. Perfekt als Geschenk, Deko oder Sammlerst\u00fcck \u2013 einmal gesehen, sofort verliebt. &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.raxxa.com\/fr\/shop\/raxxa-postkarte-suesses-baby-koala\/\" \/>\n<meta property=\"og:site_name\" content=\"raxxa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/raxxacom\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-01T16:57:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data1\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-postkarte-suesses-baby-koala\\\/\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-postkarte-suesses-baby-koala\\\/\",\"name\":\"raxxa Postkarte: S\u00fc\u00dfes Baby-Koala - raxxa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-postkarte-suesses-baby-koala\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-postkarte-suesses-baby-koala\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/raxxa-268-23418-185-Slothy-SueSses-Baby-Koala-11.jpg\",\"datePublished\":\"2026-03-01T16:56:34+00:00\",\"dateModified\":\"2026-03-01T16:57:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-postkarte-suesses-baby-koala\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-postkarte-suesses-baby-koala\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-postkarte-suesses-baby-koala\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/raxxa-268-23418-185-Slothy-SueSses-Baby-Koala-11.jpg\",\"contentUrl\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/raxxa-268-23418-185-Slothy-SueSses-Baby-Koala-11.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-postkarte-suesses-baby-koala\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.raxxa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.raxxa.com\\\/it\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"raxxa Postkarte: S\u00fc\u00dfes Baby-Koala\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#website\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/\",\"name\":\"raxxa\",\"description\":\"Einzigartige individuelle Produkte von unseren Designern\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.raxxa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#organization\",\"name\":\"raxxa\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo_v2.png\",\"contentUrl\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo_v2.png\",\"width\":380,\"height\":382,\"caption\":\"raxxa\"},\"image\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/raxxacom\"]}]}<\/script>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"1-185-23418-268\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"raxxa Postkarte: S\u00fc\u00dfes Baby-Koala - raxxa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.raxxa.com\/fr\/shop\/raxxa-postkarte-suesses-baby-koala\/","og_locale":"fr_FR","og_type":"article","og_title":"raxxa Postkarte: S\u00fc\u00dfes Baby-Koala","og_description":"&quot;S\u00fc\u00dfes Baby-Koala&quot; by Slothy Dieses Baby-Koala schmilzt Herzen im ersten Moment. Flauschiges Fell, riesige Kulleraugen und ein fr\u00f6hliches L\u00e4cheln machen es absolut unwiderstehlich. Perfekt als Geschenk, Deko oder Sammlerst\u00fcck \u2013 einmal gesehen, sofort verliebt. &nbsp;","og_url":"https:\/\/www.raxxa.com\/fr\/shop\/raxxa-postkarte-suesses-baby-koala\/","og_site_name":"raxxa","article_publisher":"https:\/\/facebook.com\/raxxacom","article_modified_time":"2026-03-01T16:57:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.raxxa.com\/shop\/raxxa-postkarte-suesses-baby-koala\/","url":"https:\/\/www.raxxa.com\/shop\/raxxa-postkarte-suesses-baby-koala\/","name":"raxxa Postkarte: S\u00fc\u00dfes Baby-Koala - raxxa","isPartOf":{"@id":"https:\/\/www.raxxa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.raxxa.com\/shop\/raxxa-postkarte-suesses-baby-koala\/#primaryimage"},"image":{"@id":"https:\/\/www.raxxa.com\/shop\/raxxa-postkarte-suesses-baby-koala\/#primaryimage"},"thumbnailUrl":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2026\/03\/raxxa-268-23418-185-Slothy-SueSses-Baby-Koala-11.jpg","datePublished":"2026-03-01T16:56:34+00:00","dateModified":"2026-03-01T16:57:53+00:00","breadcrumb":{"@id":"https:\/\/www.raxxa.com\/shop\/raxxa-postkarte-suesses-baby-koala\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.raxxa.com\/shop\/raxxa-postkarte-suesses-baby-koala\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.raxxa.com\/shop\/raxxa-postkarte-suesses-baby-koala\/#primaryimage","url":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2026\/03\/raxxa-268-23418-185-Slothy-SueSses-Baby-Koala-11.jpg","contentUrl":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2026\/03\/raxxa-268-23418-185-Slothy-SueSses-Baby-Koala-11.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/www.raxxa.com\/shop\/raxxa-postkarte-suesses-baby-koala\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.raxxa.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.raxxa.com\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"raxxa Postkarte: S\u00fc\u00dfes Baby-Koala"}]},{"@type":"WebSite","@id":"https:\/\/www.raxxa.com\/#website","url":"https:\/\/www.raxxa.com\/","name":"raxxa","description":"Des produits uniques et personnalis\u00e9s cr\u00e9\u00e9s par nos designers","publisher":{"@id":"https:\/\/www.raxxa.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.raxxa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.raxxa.com\/#organization","name":"raxxa","url":"https:\/\/www.raxxa.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.raxxa.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2022\/07\/logo_v2.png","contentUrl":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2022\/07\/logo_v2.png","width":380,"height":382,"caption":"raxxa"},"image":{"@id":"https:\/\/www.raxxa.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/raxxacom"]}]},"og_availability":"instock","product_availability":"instock","product_retailer_item_id":"1-185-23418-268","product_condition":"new"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.raxxa.com\/fr\/wp-json\/wp\/v2\/product\/289159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.raxxa.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.raxxa.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.raxxa.com\/fr\/wp-json\/wp\/v2\/comments?post=289159"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.raxxa.com\/fr\/wp-json\/wp\/v2\/media\/289160"}],"wp:attachment":[{"href":"https:\/\/www.raxxa.com\/fr\/wp-json\/wp\/v2\/media?parent=289159"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.raxxa.com\/fr\/wp-json\/wp\/v2\/product_brand?post=289159"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.raxxa.com\/fr\/wp-json\/wp\/v2\/product_cat?post=289159"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.raxxa.com\/fr\/wp-json\/wp\/v2\/product_tag?post=289159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}