{"id":206542,"date":"2024-10-03T00:02:26","date_gmt":"2024-10-02T22:02:26","guid":{"rendered":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-puzzle-yellow\/"},"modified":"2025-11-03T06:34:43","modified_gmt":"2025-11-03T04:34:43","slug":"raxxa-premium-puzzle-yellow","status":"publish","type":"product","link":"https:\/\/www.raxxa.com\/fr\/shop\/raxxa-premium-puzzle-yellow\/","title":{"rendered":"Puzzle premium raxxa : Yellow"},"content":{"rendered":"<p><span style=\"color: rgb(0, 0, 0); font-family: helvetica, sans-serif; font-size: 24px;\">Puzzle photo raxxa Premium<\/span><\/p>\n<div><span style=\"font-weight: bolder;color: rgb(0, 0, 0);\">&#8222;Yellow&#8220; by Nuria Art<\/span><\/div>\n<div><span style=\"font-weight: bolder;\"><br \/><\/span><\/div>\n<div><span style=\"font-size: 1rem;color: rgb(0, 0, 0);\">Yellow, , es una obra vibrante, positiva y alegre. La artista pretende transmitir la belleza de la vida, mediante una explosi\u00f3n de colores.<\/span><\/div>\n<div><\/div>\n<p><\/p>\n<div>\n<ul class=\"list-normal\" style=\"margin-right: 0px; margin-left: 0px; padding: 0px 0px 0px 1rem; border: 0px; text-size-adjust: none; list-style: inside none square; line-height: 26px;\">\n<li style=\"color: rgb(51, 51, 51); font-family: Lato_Light, sans-serif; font-size: 14.4px; margin: 0px; padding: 0px; border: 0px; text-size-adjust: none;\">1000 pi\u00e8ces = L 68 x H 48 cm, pi\u00e8ces du puzzle env. 1,9 x 1,6 cm.<\/li>\n<li style=\"color: rgb(51, 51, 51); font-family: Lato_Light, sans-serif; font-size: 14.4px; margin: 0px; padding: 0px; border: 0px; text-size-adjust: none;\">V\u00e9ritable carton puzzle bleu premium de 1,9 mm d'\u00e9paisseur. Les pi\u00e8ces du puzzle s'embo\u00eetent parfaitement les unes dans les autres.<\/li>\n<li style=\"color: rgb(51, 51, 51); font-family: Lato_Light, sans-serif; font-size: 14.4px; margin: 0px; padding: 0px; border: 0px; text-size-adjust: none;\">La plus haute qualit\u00e9 d'impression HD pour des d\u00e9grad\u00e9s de couleurs subtils ainsi que des couleurs brillantes et lumineuses sur un carton de haute qualit\u00e9 pour une repr\u00e9sentation tr\u00e8s fine des d\u00e9tails.<\/li>\n<li style=\"color: rgb(51, 51, 51); font-family: Lato_Light, sans-serif; font-size: 14.4px; margin: 0px; padding: 0px; border: 0px; text-size-adjust: none;\">Bo\u00eete \u00e0 couvercle coiffant, papier de lin finement gaufr\u00e9 avec un vernis de protection \u00e0 base d'eau pour une meilleure durabilit\u00e9 de la bo\u00eete.<\/li>\n<li style=\"color: rgb(51, 51, 51); font-family: Lato_Light, sans-serif; font-size: 14.4px; margin: 0px; padding: 0px; border: 0px; text-size-adjust: none;\">production enti\u00e8rement neutre pour le climat, FSC<\/li>\n<li style=\"color: rgb(51, 51, 51); font-family: Lato_Light, sans-serif; font-size: 14.4px; margin: 0px; padding: 0px; border: 0px; text-size-adjust: none;\">Fabriqu\u00e9 en Allemagne<\/li>\n<\/ul>\n<p><\/p>\n<p style=\"margin-right: 0px; margin-bottom: 0px; margin-left: 0px; padding: 0px; border: 0px; text-size-adjust: none;\"><\/p>\n<p style=\"margin-right: 0px; margin-bottom: 0px; margin-left: 0px; padding: 0px; border: 0px; text-size-adjust: none;\"><span style=\"font-size: 1rem;\">Une v\u00e9ritable pi\u00e8ce unique. Le motif que vous souhaitez n'est produit et envoy\u00e9 sp\u00e9cialement pour vous qu'apr\u00e8s r\u00e9ception de votre commande.<\/span><\/p>\n<p style=\"margin-right: 0px; margin-bottom: 0px; margin-left: 0px; padding: 0px; border: 0px; text-size-adjust: none;\"><span style=\"font-size: 1rem;\">Attention : risque d'\u00e9touffement en raison de petites pi\u00e8ces pouvant \u00eatre aval\u00e9es.<\/span><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>raxxa Premium-Fotopuzzle &#8222;Yellow&#8220; by Nuria Art Yellow, , es una obra vibrante, positiva y alegre. La artista pretende transmitir la belleza de la vida, mediante una explosi\u00f3n de colores. 1000 Teile = B 68 x H 48 cm, Puzzleteile ca. 1,9 x 1,6 cm. Echte blaue Premium-Puzzlepappe mit 1,9 mm St\u00e4rke.&nbsp;Die Puzzleteile greifen perfekt ineinander. [&hellip;]<\/p>\n","protected":false},"featured_media":253111,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[137,12508,10365],"product_tag":[12563],"class_list":["post-206542","product","type-product","status-publish","has-post-thumbnail","product_cat-abstrakt","product_cat-nuria-art","product_cat-puzzle","product_tag-arte-art-artbasel-natur-colors-raxxa-artforsale-artforsalebyartist-artforsaleonline-artecontemporanea-present-happy-arteterapia-contemporary-originalart","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>raxxa Premium-Puzzle: Yellow - raxxa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.raxxa.com\/fr\/shop\/raxxa-premium-puzzle-yellow\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"raxxa Premium-Puzzle: Yellow\" \/>\n<meta property=\"og:description\" content=\"raxxa Premium-Fotopuzzle &#8222;Yellow&#8220; by Nuria Art Yellow, , es una obra vibrante, positiva y alegre. La artista pretende transmitir la belleza de la vida, mediante una explosi\u00f3n de colores. 1000 Teile = B 68 x H 48 cm, Puzzleteile ca. 1,9 x 1,6 cm. Echte blaue Premium-Puzzlepappe mit 1,9 mm St\u00e4rke.&nbsp;Die Puzzleteile greifen perfekt ineinander. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.raxxa.com\/fr\/shop\/raxxa-premium-puzzle-yellow\/\" \/>\n<meta property=\"og:site_name\" content=\"raxxa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/raxxacom\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-03T04:34:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.raxxa.com\/wp-content\/uploads\/2024\/10\/raxxa-puzzle-324-17845-Nuria-Art-Yellow-box-1024x683.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;29,99\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-puzzle-yellow\\\/\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-puzzle-yellow\\\/\",\"name\":\"raxxa Premium-Puzzle: Yellow - raxxa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-puzzle-yellow\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-puzzle-yellow\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/raxxa-puzzle-324-17845-Nuria-Art-Yellow-box.png\",\"datePublished\":\"2024-10-02T22:02:26+00:00\",\"dateModified\":\"2025-11-03T04:34:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-puzzle-yellow\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-puzzle-yellow\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-puzzle-yellow\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/raxxa-puzzle-324-17845-Nuria-Art-Yellow-box.png\",\"contentUrl\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/raxxa-puzzle-324-17845-Nuria-Art-Yellow-box.png\",\"width\":2400,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-puzzle-yellow\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.raxxa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.raxxa.com\\\/it\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"raxxa Premium-Puzzle: Yellow\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#website\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/\",\"name\":\"raxxa\",\"description\":\"Einzigartige individuelle Produkte von unseren Designern\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.raxxa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#organization\",\"name\":\"raxxa\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo_v2.png\",\"contentUrl\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo_v2.png\",\"width\":380,\"height\":382,\"caption\":\"raxxa\"},\"image\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/raxxacom\"]}]}<\/script>\n<meta property=\"product:price:amount\" content=\"29.99\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"1-14270-17845-324\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Puzzle premium raxxa : Yellow - raxxa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.raxxa.com\/fr\/shop\/raxxa-premium-puzzle-yellow\/","og_locale":"fr_FR","og_type":"article","og_title":"raxxa Premium-Puzzle: Yellow","og_description":"raxxa Premium-Fotopuzzle &#8222;Yellow&#8220; by Nuria Art Yellow, , es una obra vibrante, positiva y alegre. La artista pretende transmitir la belleza de la vida, mediante una explosi\u00f3n de colores. 1000 Teile = B 68 x H 48 cm, Puzzleteile ca. 1,9 x 1,6 cm. Echte blaue Premium-Puzzlepappe mit 1,9 mm St\u00e4rke.&nbsp;Die Puzzleteile greifen perfekt ineinander. [&hellip;]","og_url":"https:\/\/www.raxxa.com\/fr\/shop\/raxxa-premium-puzzle-yellow\/","og_site_name":"raxxa","article_publisher":"https:\/\/facebook.com\/raxxacom","article_modified_time":"2025-11-03T04:34:43+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2024\/10\/raxxa-puzzle-324-17845-Nuria-Art-Yellow-box-1024x683.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"&euro;29,99","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-puzzle-yellow\/","url":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-puzzle-yellow\/","name":"Puzzle premium raxxa : Yellow - raxxa","isPartOf":{"@id":"https:\/\/www.raxxa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-puzzle-yellow\/#primaryimage"},"image":{"@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-puzzle-yellow\/#primaryimage"},"thumbnailUrl":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2024\/10\/raxxa-puzzle-324-17845-Nuria-Art-Yellow-box.png","datePublished":"2024-10-02T22:02:26+00:00","dateModified":"2025-11-03T04:34:43+00:00","breadcrumb":{"@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-puzzle-yellow\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.raxxa.com\/shop\/raxxa-premium-puzzle-yellow\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-puzzle-yellow\/#primaryimage","url":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2024\/10\/raxxa-puzzle-324-17845-Nuria-Art-Yellow-box.png","contentUrl":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2024\/10\/raxxa-puzzle-324-17845-Nuria-Art-Yellow-box.png","width":2400,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-puzzle-yellow\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.raxxa.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.raxxa.com\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"raxxa Premium-Puzzle: Yellow"}]},{"@type":"WebSite","@id":"https:\/\/www.raxxa.com\/#website","url":"https:\/\/www.raxxa.com\/","name":"raxxa","description":"Des produits uniques et personnalis\u00e9s cr\u00e9\u00e9s par nos designers","publisher":{"@id":"https:\/\/www.raxxa.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.raxxa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.raxxa.com\/#organization","name":"raxxa","url":"https:\/\/www.raxxa.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.raxxa.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2022\/07\/logo_v2.png","contentUrl":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2022\/07\/logo_v2.png","width":380,"height":382,"caption":"raxxa"},"image":{"@id":"https:\/\/www.raxxa.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/raxxacom"]}]},"product_price_amount":"29.99","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"1-14270-17845-324","product_condition":"new"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.raxxa.com\/fr\/wp-json\/wp\/v2\/product\/206542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.raxxa.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.raxxa.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.raxxa.com\/fr\/wp-json\/wp\/v2\/comments?post=206542"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.raxxa.com\/fr\/wp-json\/wp\/v2\/media\/253111"}],"wp:attachment":[{"href":"https:\/\/www.raxxa.com\/fr\/wp-json\/wp\/v2\/media?parent=206542"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.raxxa.com\/fr\/wp-json\/wp\/v2\/product_brand?post=206542"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.raxxa.com\/fr\/wp-json\/wp\/v2\/product_cat?post=206542"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.raxxa.com\/fr\/wp-json\/wp\/v2\/product_tag?post=206542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}