{"id":315137,"date":"2026-04-10T13:03:28","date_gmt":"2026-04-10T11:03:28","guid":{"rendered":"https:\/\/www.raxxa.com\/shop\/kissen-oh-alles-unser-kaese-schwarze-und-weisse-maus-im-kaeseland\/"},"modified":"2026-04-10T13:07:22","modified_gmt":"2026-04-10T11:07:22","slug":"kissen-oh-alles-unser-kaese-schwarze-und-weisse-maus-im-kaeseland","status":"publish","type":"product","link":"https:\/\/www.raxxa.com\/en\/shop\/kissen-oh-alles-unser-kaese-schwarze-und-weisse-maus-im-kaeseland\/","title":{"rendered":"Kissen: Oh, alles unser K\u00e4se &#8211; schwarze und wei\u00dfe Maus im K\u00e4seland"},"content":{"rendered":"<div><span style='font-weight: bolder;font-size: 1rem'>raxxa Premium Kissen Oh, alles unser K\u00e4se &#8211; schwarze und wei\u00dfe Maus im K\u00e4seland<\/span><\/div>\n<div><span style='font-weight: bolder'>designed by Kerstin Waurick<\/span><\/div>\n<div><span style='font-size: 1rem'><br \/><\/span><span style='font-size: 1rem'>Mit jedem Kauf eines raxxa Produkts wird direkt ein K\u00fcnstler unterst\u00fctzt.<\/span><\/div>\n<div><span style='font-weight: bolder'><br \/><\/span><\/div>\n<div>Diese charmanten, stilisierten 3D-Illustrationen zeigen drollige M\u00e4use in humorvollen Szenen rund um ihre gro\u00dfe Leidenschaft- K\u00e4se. Ob beim Staunen, Schlemmen, Stehlen oder darin kuscheln \u2013 jede Maus bringt Witz, Neugier und Pers\u00f6nlichkeit auf den Bildschirm. Die Motive wurden mithilfe moderner KI gestaltet und verbinden lebendige Charaktere mit fantasievollen, niedlichen Situationen. So entsteht eine verspielte Bildwelt voller Humor, Charme und kleiner Abenteuer, die Fans von Tieren und Comic-Illustrationen begeistern wird.<\/div>\n<div><span style='font-size: 1rem'>Dieses raxxa Premium-Kissen im trendigen Design ist der perfekte Deko-Akzent als besonderer Blickfang zum Wohlf\u00fchlen. Wirkungsvoll zur Geltung kommt es auf dem Bett, Sessel und der Couch. Es f\u00fchlt sich wie hochwertiges Leinen an und dient als zeitgem\u00e4\u00dfes Einrichtungselement.<\/span><\/div>\n<div>  <span style='font-size: 1rem'><br \/><\/span><span style='font-size: 1rem'>Materialhinweise:<\/span><\/div>\n<p><\/p>\n<div><span style='font-size: 1rem'><\/p>\n<ul>\n<li>100 % vorgeschrumpfte Polyesterh\u00fclle<\/li>\n<li>Stoffgewicht: 275 g\/m\u00b2<\/li>\n<li>Leinen\u00e4hnlicher Stoff<\/li>\n<li>Feiner Druck auf beiden Seiten der Kissenh\u00fclle<\/li>\n<li>Verborgener Rei\u00dfverschluss<\/li>\n<li>H\u00fclle kann in der Waschmaschine gewaschen werden<\/li>\n<li>Inkl. formbest\u00e4ndige 100 % Polyesterf\u00fcllung (darf nur von Hand gewaschen werden)<\/li>\n<\/ul>\n<p><\/span><\/div>\n<div>  <span style='font-size: 1rem'><br \/><\/span><span style='font-size: 1rem'>Gr\u00f6ssenhinweise in cm \/ Zoll:<\/span><\/div>\n<p><\/p>\n<table cellspacing='5' cellpadding='5' border='1'>\n<tbody>\n<tr>\n<td><b>Gr\u00f6sse [cm \/ Zoll]<\/b><\/td>\n<td><b>Breite [cm \/ Zoll]<\/b><\/td>\n<td><b>L\u00e4nge [cm \/ Zoll]<\/b><\/td>\n<td><b>Tiefe [cm \/ Zoll]<\/b><\/td>\n<td><b>L\u00e4nge des Reisverschlusses [cm \/ Zoll]<\/b><\/td>\n<\/tr>\n<tr>\n<td>45 x 45 cm \/ 18\u2033 \u00d7 18\u2033<\/td>\n<td>45 cm \/ 18\u2033<\/td>\n<td>45 cm \/ 18\u2033<\/td>\n<td>12.5 cm \/ 4 \u215e<\/td>\n<td>39 cm \/ 15 \u215c<\/td>\n<\/tr>\n<tr>\n<td>50 x 30 cm \/ 20\u2033 \u00d7 12\u2033<\/td>\n<td>50 cm \/ 20\u2033<\/td>\n<td>30 cm \/ 12\u2033<\/td>\n<td>12.5 cm \/ 4 \u215e<\/td>\n<td>43 cm \/ 16 \u215e<\/td>\n<\/tr>\n<tr>\n<td>56 x 56 cm \/ 22\u2033 \u00d7 22\u2033<\/td>\n<td>56 cm \/ 22\u2033<\/td>\n<td>56 cm \/ 22\u2033<\/td>\n<td>12.5 cm \/  4 \u215e<\/td>\n<td>48 cm \/ 18 \u215e<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/p>\n<div><span style='font-size: 1rem'>Alle Produkte der raxxa-Kollektion werden extra f\u00fcr Sie in dem gew\u00fcnschten Design und\u00a0Gr\u00f6\u00dfe nach Ihrem Bestelleingang hergestellt.&nbsp;<\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>raxxa Premium Kissen Oh, alles unser K\u00e4se &#8211; schwarze und wei\u00dfe Maus im K\u00e4seland designed by Kerstin Waurick Mit jedem Kauf eines raxxa Produkts wird direkt ein K\u00fcnstler unterst\u00fctzt. Diese charmanten, stilisierten 3D-Illustrationen zeigen drollige M\u00e4use in humorvollen Szenen rund um ihre gro\u00dfe Leidenschaft- K\u00e4se. Ob beim Staunen, Schlemmen, Stehlen oder darin kuscheln \u2013 jede [&hellip;]<\/p>\n","protected":false},"featured_media":315139,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[10313,10314,13429],"product_tag":[],"class_list":["post-315137","product","type-product","status-publish","has-post-thumbnail","product_cat-home-living","product_cat-kissen","product_cat-kerstin-waurick","product_shipping_class-versand-t-shirts1","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kissen: Oh, alles unser K\u00e4se - schwarze und wei\u00dfe Maus im K\u00e4seland - raxxa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.raxxa.com\/en\/shop\/kissen-oh-alles-unser-kaese-schwarze-und-weisse-maus-im-kaeseland\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kissen: Oh, alles unser K\u00e4se - schwarze und wei\u00dfe Maus im K\u00e4seland\" \/>\n<meta property=\"og:description\" content=\"raxxa Premium Kissen Oh, alles unser K\u00e4se &#8211; schwarze und wei\u00dfe Maus im K\u00e4seland designed by Kerstin Waurick Mit jedem Kauf eines raxxa Produkts wird direkt ein K\u00fcnstler unterst\u00fctzt. Diese charmanten, stilisierten 3D-Illustrationen zeigen drollige M\u00e4use in humorvollen Szenen rund um ihre gro\u00dfe Leidenschaft- K\u00e4se. Ob beim Staunen, Schlemmen, Stehlen oder darin kuscheln \u2013 jede [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.raxxa.com\/en\/shop\/kissen-oh-alles-unser-kaese-schwarze-und-weisse-maus-im-kaeseland\/\" \/>\n<meta property=\"og:site_name\" content=\"raxxa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/raxxacom\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-10T11:07:22+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data1\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/kissen-oh-alles-unser-kaese-schwarze-und-weisse-maus-im-kaeseland\\\/\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/kissen-oh-alles-unser-kaese-schwarze-und-weisse-maus-im-kaeseland\\\/\",\"name\":\"Kissen: Oh, alles unser K\u00e4se - schwarze und wei\u00dfe Maus im K\u00e4seland - raxxa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/kissen-oh-alles-unser-kaese-schwarze-und-weisse-maus-im-kaeseland\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/kissen-oh-alles-unser-kaese-schwarze-und-weisse-maus-im-kaeseland\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/raxxa-Kissen-373-24091-112-Kerstin-Waurick-Oh-alles-unser-Kase-schwarze-und-weiSse-Maus-im-Kaseland-4.jpg\",\"datePublished\":\"2026-04-10T11:03:28+00:00\",\"dateModified\":\"2026-04-10T11:07:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/kissen-oh-alles-unser-kaese-schwarze-und-weisse-maus-im-kaeseland\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/kissen-oh-alles-unser-kaese-schwarze-und-weisse-maus-im-kaeseland\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/kissen-oh-alles-unser-kaese-schwarze-und-weisse-maus-im-kaeseland\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/raxxa-Kissen-373-24091-112-Kerstin-Waurick-Oh-alles-unser-Kase-schwarze-und-weiSse-Maus-im-Kaseland-4.jpg\",\"contentUrl\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/raxxa-Kissen-373-24091-112-Kerstin-Waurick-Oh-alles-unser-Kase-schwarze-und-weiSse-Maus-im-Kaseland-4.jpg\",\"width\":2100,\"height\":2100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/kissen-oh-alles-unser-kaese-schwarze-und-weisse-maus-im-kaeseland\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.raxxa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.raxxa.com\\\/it\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kissen: Oh, alles unser K\u00e4se &#8211; schwarze und wei\u00dfe Maus im K\u00e4seland\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#website\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/\",\"name\":\"raxxa\",\"description\":\"Einzigartige individuelle Produkte von unseren Designern\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.raxxa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#organization\",\"name\":\"raxxa\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo_v2.png\",\"contentUrl\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo_v2.png\",\"width\":380,\"height\":382,\"caption\":\"raxxa\"},\"image\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/raxxacom\"]}]}<\/script>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"1-112-24091-373\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kissen: Oh, alles unser K\u00e4se - schwarze und wei\u00dfe Maus im K\u00e4seland - raxxa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.raxxa.com\/en\/shop\/kissen-oh-alles-unser-kaese-schwarze-und-weisse-maus-im-kaeseland\/","og_locale":"en_US","og_type":"article","og_title":"Kissen: Oh, alles unser K\u00e4se - schwarze und wei\u00dfe Maus im K\u00e4seland","og_description":"raxxa Premium Kissen Oh, alles unser K\u00e4se &#8211; schwarze und wei\u00dfe Maus im K\u00e4seland designed by Kerstin Waurick Mit jedem Kauf eines raxxa Produkts wird direkt ein K\u00fcnstler unterst\u00fctzt. Diese charmanten, stilisierten 3D-Illustrationen zeigen drollige M\u00e4use in humorvollen Szenen rund um ihre gro\u00dfe Leidenschaft- K\u00e4se. Ob beim Staunen, Schlemmen, Stehlen oder darin kuscheln \u2013 jede [&hellip;]","og_url":"https:\/\/www.raxxa.com\/en\/shop\/kissen-oh-alles-unser-kaese-schwarze-und-weisse-maus-im-kaeseland\/","og_site_name":"raxxa","article_publisher":"https:\/\/facebook.com\/raxxacom","article_modified_time":"2026-04-10T11:07:22+00:00","twitter_card":"summary_large_image","twitter_misc":{"Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.raxxa.com\/shop\/kissen-oh-alles-unser-kaese-schwarze-und-weisse-maus-im-kaeseland\/","url":"https:\/\/www.raxxa.com\/shop\/kissen-oh-alles-unser-kaese-schwarze-und-weisse-maus-im-kaeseland\/","name":"Kissen: Oh, alles unser K\u00e4se - schwarze und wei\u00dfe Maus im K\u00e4seland - raxxa","isPartOf":{"@id":"https:\/\/www.raxxa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.raxxa.com\/shop\/kissen-oh-alles-unser-kaese-schwarze-und-weisse-maus-im-kaeseland\/#primaryimage"},"image":{"@id":"https:\/\/www.raxxa.com\/shop\/kissen-oh-alles-unser-kaese-schwarze-und-weisse-maus-im-kaeseland\/#primaryimage"},"thumbnailUrl":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2026\/04\/raxxa-Kissen-373-24091-112-Kerstin-Waurick-Oh-alles-unser-Kase-schwarze-und-weiSse-Maus-im-Kaseland-4.jpg","datePublished":"2026-04-10T11:03:28+00:00","dateModified":"2026-04-10T11:07:22+00:00","breadcrumb":{"@id":"https:\/\/www.raxxa.com\/shop\/kissen-oh-alles-unser-kaese-schwarze-und-weisse-maus-im-kaeseland\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.raxxa.com\/shop\/kissen-oh-alles-unser-kaese-schwarze-und-weisse-maus-im-kaeseland\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.raxxa.com\/shop\/kissen-oh-alles-unser-kaese-schwarze-und-weisse-maus-im-kaeseland\/#primaryimage","url":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2026\/04\/raxxa-Kissen-373-24091-112-Kerstin-Waurick-Oh-alles-unser-Kase-schwarze-und-weiSse-Maus-im-Kaseland-4.jpg","contentUrl":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2026\/04\/raxxa-Kissen-373-24091-112-Kerstin-Waurick-Oh-alles-unser-Kase-schwarze-und-weiSse-Maus-im-Kaseland-4.jpg","width":2100,"height":2100},{"@type":"BreadcrumbList","@id":"https:\/\/www.raxxa.com\/shop\/kissen-oh-alles-unser-kaese-schwarze-und-weisse-maus-im-kaeseland\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.raxxa.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.raxxa.com\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"Kissen: Oh, alles unser K\u00e4se &#8211; schwarze und wei\u00dfe Maus im K\u00e4seland"}]},{"@type":"WebSite","@id":"https:\/\/www.raxxa.com\/#website","url":"https:\/\/www.raxxa.com\/","name":"raxxa","description":"Unique individual products from our designers","publisher":{"@id":"https:\/\/www.raxxa.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.raxxa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.raxxa.com\/#organization","name":"raxxa","url":"https:\/\/www.raxxa.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.raxxa.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2022\/07\/logo_v2.png","contentUrl":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2022\/07\/logo_v2.png","width":380,"height":382,"caption":"raxxa"},"image":{"@id":"https:\/\/www.raxxa.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/raxxacom"]}]},"og_availability":"instock","product_availability":"instock","product_retailer_item_id":"1-112-24091-373","product_condition":"new"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.raxxa.com\/en\/wp-json\/wp\/v2\/product\/315137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.raxxa.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.raxxa.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.raxxa.com\/en\/wp-json\/wp\/v2\/comments?post=315137"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.raxxa.com\/en\/wp-json\/wp\/v2\/media\/315139"}],"wp:attachment":[{"href":"https:\/\/www.raxxa.com\/en\/wp-json\/wp\/v2\/media?parent=315137"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.raxxa.com\/en\/wp-json\/wp\/v2\/product_brand?post=315137"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.raxxa.com\/en\/wp-json\/wp\/v2\/product_cat?post=315137"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.raxxa.com\/en\/wp-json\/wp\/v2\/product_tag?post=315137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}