{"id":234198,"date":"2025-07-30T15:23:50","date_gmt":"2025-07-30T13:23:50","guid":{"rendered":"https:\/\/www.raxxa.com\/?post_type=product&#038;p=234198"},"modified":"2025-07-30T15:26:27","modified_gmt":"2025-07-30T13:26:27","slug":"raxxa-postkarte-heute-erledige-ich-nichts-und-morgen-vielleicht-noch-weniger","status":"publish","type":"product","link":"https:\/\/www.raxxa.com\/en\/shop\/raxxa-postkarte-heute-erledige-ich-nichts-und-morgen-vielleicht-noch-weniger\/","title":{"rendered":"raxxa Postkarte: Heute erledige ich nichts und morgen vielleicht noch weniger"},"content":{"rendered":"<h3><strong>&quot;Heute erledige ich nichts und morgen vielleicht noch weniger&quot; by Steffen Gierok-Latniak<\/strong><\/h3>\n<p><strong><\/strong><\/p>\n<\/p>\n<p>&nbsp;<\/p>\n<ul><li>We print your desired postcard blank or with a personal greeting and send it worldwide to any person or to yourself.<\/li><li>Ideal for online postcrossing or individual greetings to your loved ones, friends, relatives and acquaintances.<\/li><li>Alternatively, as a pure motif blank card to collect or send yourself.<\/li><li>Postcards DIN A6 (14.8 cm x 10.5 cm).<\/li><\/ul><br><br><b>How do I create\/design my personal postcard?<\/b><br><br>1) Simply enter the text of your message or greeting (max. 500 characters).<br>2) If you want to send your postcard for Postcrossing, enter the PostcrossingID.<br>Otherwise, simply leave this field blank.<br>3) Enter the first and last name, street + house number, postal code, city and country for the desired recipient of the postcard in the input fields.<br>4) You can now add your designed postcard to the shopping cart and order it at the checkout.<br><br>We will now print your personalized postcard, stamp it and send it to your specified recipient.<br><br>If you have any questions, simply send us a message or email<br>","protected":false},"excerpt":{"rendered":"<p>&quot;Heute erledige ich nichts und morgen vielleicht noch weniger&quot; by Steffen Gierok-Latniak &nbsp;<\/p>","protected":false},"featured_media":234229,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[12580,135,11884],"product_tag":[],"class_list":["post-234198","product","type-product","status-publish","has-post-thumbnail","product_cat-steffen-gierok","product_cat-planzen","product_cat-postkarten","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>raxxa Postkarte: Heute erledige ich nichts und morgen vielleicht noch weniger - raxxa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.raxxa.com\/en\/shop\/raxxa-postkarte-heute-erledige-ich-nichts-und-morgen-vielleicht-noch-weniger\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"raxxa Postkarte: Heute erledige ich nichts und morgen vielleicht noch weniger\" \/>\n<meta property=\"og:description\" content=\"&quot;Heute erledige ich nichts und morgen vielleicht noch weniger&quot; by Steffen Gierok-Latniak &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.raxxa.com\/en\/shop\/raxxa-postkarte-heute-erledige-ich-nichts-und-morgen-vielleicht-noch-weniger\/\" \/>\n<meta property=\"og:site_name\" content=\"raxxa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/raxxacom\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-30T13:26:27+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data1\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-postkarte-heute-erledige-ich-nichts-und-morgen-vielleicht-noch-weniger\\\/\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-postkarte-heute-erledige-ich-nichts-und-morgen-vielleicht-noch-weniger\\\/\",\"name\":\"raxxa Postkarte: Heute erledige ich nichts und morgen vielleicht noch weniger - raxxa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-postkarte-heute-erledige-ich-nichts-und-morgen-vielleicht-noch-weniger\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-postkarte-heute-erledige-ich-nichts-und-morgen-vielleicht-noch-weniger\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/raxxa-331-18784-185-Steffen-Gierok-Latniak-Heute-erledige-ich-nichts-\u2013-und-morgen-vielleicht-noch-weniger-17.jpg\",\"datePublished\":\"2025-07-30T13:23:50+00:00\",\"dateModified\":\"2025-07-30T13:26:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-postkarte-heute-erledige-ich-nichts-und-morgen-vielleicht-noch-weniger\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-postkarte-heute-erledige-ich-nichts-und-morgen-vielleicht-noch-weniger\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-postkarte-heute-erledige-ich-nichts-und-morgen-vielleicht-noch-weniger\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/raxxa-331-18784-185-Steffen-Gierok-Latniak-Heute-erledige-ich-nichts-\u2013-und-morgen-vielleicht-noch-weniger-17.jpg\",\"contentUrl\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/raxxa-331-18784-185-Steffen-Gierok-Latniak-Heute-erledige-ich-nichts-\u2013-und-morgen-vielleicht-noch-weniger-17.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-postkarte-heute-erledige-ich-nichts-und-morgen-vielleicht-noch-weniger\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.raxxa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.raxxa.com\\\/it\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"raxxa Postkarte: Heute erledige ich nichts und morgen vielleicht noch weniger\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#website\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/\",\"name\":\"raxxa\",\"description\":\"Einzigartige individuelle Produkte von unseren Designern\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.raxxa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#organization\",\"name\":\"raxxa\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo_v2.png\",\"contentUrl\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo_v2.png\",\"width\":380,\"height\":382,\"caption\":\"raxxa\"},\"image\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/raxxacom\"]}]}<\/script>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"1-185-18784-331\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"raxxa Postkarte: Heute erledige ich nichts und morgen vielleicht noch weniger - raxxa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.raxxa.com\/en\/shop\/raxxa-postkarte-heute-erledige-ich-nichts-und-morgen-vielleicht-noch-weniger\/","og_locale":"en_US","og_type":"article","og_title":"raxxa Postkarte: Heute erledige ich nichts und morgen vielleicht noch weniger","og_description":"&quot;Heute erledige ich nichts und morgen vielleicht noch weniger&quot; by Steffen Gierok-Latniak &nbsp;","og_url":"https:\/\/www.raxxa.com\/en\/shop\/raxxa-postkarte-heute-erledige-ich-nichts-und-morgen-vielleicht-noch-weniger\/","og_site_name":"raxxa","article_publisher":"https:\/\/facebook.com\/raxxacom","article_modified_time":"2025-07-30T13:26:27+00:00","twitter_card":"summary_large_image","twitter_misc":{"Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.raxxa.com\/shop\/raxxa-postkarte-heute-erledige-ich-nichts-und-morgen-vielleicht-noch-weniger\/","url":"https:\/\/www.raxxa.com\/shop\/raxxa-postkarte-heute-erledige-ich-nichts-und-morgen-vielleicht-noch-weniger\/","name":"raxxa Postkarte: Heute erledige ich nichts und morgen vielleicht noch weniger - raxxa","isPartOf":{"@id":"https:\/\/www.raxxa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.raxxa.com\/shop\/raxxa-postkarte-heute-erledige-ich-nichts-und-morgen-vielleicht-noch-weniger\/#primaryimage"},"image":{"@id":"https:\/\/www.raxxa.com\/shop\/raxxa-postkarte-heute-erledige-ich-nichts-und-morgen-vielleicht-noch-weniger\/#primaryimage"},"thumbnailUrl":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2025\/07\/raxxa-331-18784-185-Steffen-Gierok-Latniak-Heute-erledige-ich-nichts-\u2013-und-morgen-vielleicht-noch-weniger-17.jpg","datePublished":"2025-07-30T13:23:50+00:00","dateModified":"2025-07-30T13:26:27+00:00","breadcrumb":{"@id":"https:\/\/www.raxxa.com\/shop\/raxxa-postkarte-heute-erledige-ich-nichts-und-morgen-vielleicht-noch-weniger\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.raxxa.com\/shop\/raxxa-postkarte-heute-erledige-ich-nichts-und-morgen-vielleicht-noch-weniger\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.raxxa.com\/shop\/raxxa-postkarte-heute-erledige-ich-nichts-und-morgen-vielleicht-noch-weniger\/#primaryimage","url":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2025\/07\/raxxa-331-18784-185-Steffen-Gierok-Latniak-Heute-erledige-ich-nichts-\u2013-und-morgen-vielleicht-noch-weniger-17.jpg","contentUrl":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2025\/07\/raxxa-331-18784-185-Steffen-Gierok-Latniak-Heute-erledige-ich-nichts-\u2013-und-morgen-vielleicht-noch-weniger-17.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/www.raxxa.com\/shop\/raxxa-postkarte-heute-erledige-ich-nichts-und-morgen-vielleicht-noch-weniger\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.raxxa.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.raxxa.com\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"raxxa Postkarte: Heute erledige ich nichts und morgen vielleicht noch weniger"}]},{"@type":"WebSite","@id":"https:\/\/www.raxxa.com\/#website","url":"https:\/\/www.raxxa.com\/","name":"raxxa","description":"Unique individual products from our designers","publisher":{"@id":"https:\/\/www.raxxa.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.raxxa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.raxxa.com\/#organization","name":"raxxa","url":"https:\/\/www.raxxa.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.raxxa.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2022\/07\/logo_v2.png","contentUrl":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2022\/07\/logo_v2.png","width":380,"height":382,"caption":"raxxa"},"image":{"@id":"https:\/\/www.raxxa.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/raxxacom"]}]},"og_availability":"instock","product_availability":"instock","product_retailer_item_id":"1-185-18784-331","product_condition":"new"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.raxxa.com\/en\/wp-json\/wp\/v2\/product\/234198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.raxxa.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.raxxa.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.raxxa.com\/en\/wp-json\/wp\/v2\/comments?post=234198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.raxxa.com\/en\/wp-json\/wp\/v2\/media\/234229"}],"wp:attachment":[{"href":"https:\/\/www.raxxa.com\/en\/wp-json\/wp\/v2\/media?parent=234198"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.raxxa.com\/en\/wp-json\/wp\/v2\/product_brand?post=234198"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.raxxa.com\/en\/wp-json\/wp\/v2\/product_cat?post=234198"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.raxxa.com\/en\/wp-json\/wp\/v2\/product_tag?post=234198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}