{"id":225689,"date":"2025-05-10T18:22:38","date_gmt":"2025-05-10T16:22:38","guid":{"rendered":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-tasse-poemas-de-hojas-y-corazones-que-vuelan-con-el-viento\/"},"modified":"2025-05-10T18:22:39","modified_gmt":"2025-05-10T16:22:39","slug":"raxxa-premium-tasse-poemas-de-hojas-y-corazones-que-vuelan-con-el-viento","status":"publish","type":"product","link":"https:\/\/www.raxxa.com\/en\/shop\/raxxa-premium-tasse-poemas-de-hojas-y-corazones-que-vuelan-con-el-viento\/","title":{"rendered":"raxxa Premium-Tasse: Poemas de hojas y corazones que vuelan con el viento"},"content":{"rendered":"<h3><strong>\"Poemas de hojas y corazones que vuelan con el viento\" by Toc de Groc<\/strong><\/h3>\n<p><strong><\/strong><\/p>\n<p>Estampado que parece baile de peque\u00f1as hojas y corazones<\/p>\n<p>&nbsp;<\/p>\n<ul><li>DIMENSIONEN: Mit Ma\u00dfen von H\u00f6he: 95 mm, \u00d8 80 mm und einer Kapazit\u00e4t von ca. 330ml ist sie die ideale Wahl f\u00fcr jeden Kaffeeliebhaber oder Teetrinker.<\/li><li>LANGLEBIG: Diese weisse Keramik-Tasse ist sowohl sp\u00fclmaschinen- als auch mikrowellenfest.<\/li><li>SPEZIELL: Jedes St\u00fcck ist ein ganz besonderes individuelles Produkt und wird erst nach der Bestellung extra f\u00fcr Sie mit Ihrem Wunschmotiv angefertigt.<\/li><li>ECHTES HANDWERK: Die Tassen werden mit Sorgfalt in Deutschland bedruckt, garantieren Langlebigkeit der Designs und sind das perfekte Geschenk.<\/li><li>UNTERST\u00dcTZUNG: Mit Ihrem Kauf eines raxxa-Produkts wird direkt ein K\u00fcnstler aus unserer raxxa-Community von aktuell \u00fcber 200 K\u00fcnstlern \/ Designern \/ Fotografen unterst\u00fctzt.<\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>&quot;Poemas de hojas y corazones que vuelan con el viento&quot; by Toc de Groc Estampado que parece baile de peque\u00f1as hojas y corazones &nbsp;<\/p>","protected":false},"featured_media":238170,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[11606,133,12936],"product_tag":[13042],"class_list":["post-225689","product","type-product","status-publish","has-post-thumbnail","product_cat-tassen","product_cat-tiere","product_cat-toc-de-groc","product_tag-cute-illustration-flowers-jardin-otono-pajaros-birds-flores-lazo-nature-natura-romantico-love-amor-corazon-color-colorsofnature","product_shipping_class-versand-tassen","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>raxxa Premium-Tasse: Poemas de hojas y corazones que vuelan con el viento - raxxa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.raxxa.com\/en\/shop\/raxxa-premium-tasse-poemas-de-hojas-y-corazones-que-vuelan-con-el-viento\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"raxxa Premium-Tasse: Poemas de hojas y corazones que vuelan con el viento\" \/>\n<meta property=\"og:description\" content=\"&quot;Poemas de hojas y corazones que vuelan con el viento&quot; by Toc de Groc Estampado que parece baile de peque\u00f1as hojas y corazones &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.raxxa.com\/en\/shop\/raxxa-premium-tasse-poemas-de-hojas-y-corazones-que-vuelan-con-el-viento\/\" \/>\n<meta property=\"og:site_name\" content=\"raxxa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/raxxacom\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-10T16:22:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;18,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-tasse-poemas-de-hojas-y-corazones-que-vuelan-con-el-viento\\\/\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-tasse-poemas-de-hojas-y-corazones-que-vuelan-con-el-viento\\\/\",\"name\":\"raxxa Premium-Tasse: Poemas de hojas y corazones que vuelan con el viento - raxxa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-tasse-poemas-de-hojas-y-corazones-que-vuelan-con-el-viento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-tasse-poemas-de-hojas-y-corazones-que-vuelan-con-el-viento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/raxxa-Tasse-346-19860-143-Toc-de-Groc-Poemas-de-hojas-y-corazones-que-vuelan-con-el-viento-1-scaled.png\",\"datePublished\":\"2025-05-10T16:22:38+00:00\",\"dateModified\":\"2025-05-10T16:22:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-tasse-poemas-de-hojas-y-corazones-que-vuelan-con-el-viento\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-tasse-poemas-de-hojas-y-corazones-que-vuelan-con-el-viento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-tasse-poemas-de-hojas-y-corazones-que-vuelan-con-el-viento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/raxxa-Tasse-346-19860-143-Toc-de-Groc-Poemas-de-hojas-y-corazones-que-vuelan-con-el-viento-1-scaled.png\",\"contentUrl\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/raxxa-Tasse-346-19860-143-Toc-de-Groc-Poemas-de-hojas-y-corazones-que-vuelan-con-el-viento-1-scaled.png\",\"width\":2560,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/shop\\\/raxxa-premium-tasse-poemas-de-hojas-y-corazones-que-vuelan-con-el-viento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.raxxa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.raxxa.com\\\/it\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"raxxa Premium-Tasse: Poemas de hojas y corazones que vuelan con el viento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#website\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/\",\"name\":\"raxxa\",\"description\":\"Einzigartige individuelle Produkte von unseren Designern\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.raxxa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#organization\",\"name\":\"raxxa\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo_v2.png\",\"contentUrl\":\"https:\\\/\\\/www.raxxa.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo_v2.png\",\"width\":380,\"height\":382,\"caption\":\"raxxa\"},\"image\":{\"@id\":\"https:\\\/\\\/www.raxxa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/raxxacom\"]}]}<\/script>\n<meta property=\"product:price:amount\" content=\"18.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"1-14518-19860-346\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"raxxa Premium-Tasse: Poemas de hojas y corazones que vuelan con el viento - raxxa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.raxxa.com\/en\/shop\/raxxa-premium-tasse-poemas-de-hojas-y-corazones-que-vuelan-con-el-viento\/","og_locale":"en_US","og_type":"article","og_title":"raxxa Premium-Tasse: Poemas de hojas y corazones que vuelan con el viento","og_description":"&quot;Poemas de hojas y corazones que vuelan con el viento&quot; by Toc de Groc Estampado que parece baile de peque\u00f1as hojas y corazones &nbsp;","og_url":"https:\/\/www.raxxa.com\/en\/shop\/raxxa-premium-tasse-poemas-de-hojas-y-corazones-que-vuelan-con-el-viento\/","og_site_name":"raxxa","article_publisher":"https:\/\/facebook.com\/raxxacom","article_modified_time":"2025-05-10T16:22:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;18,90","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-tasse-poemas-de-hojas-y-corazones-que-vuelan-con-el-viento\/","url":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-tasse-poemas-de-hojas-y-corazones-que-vuelan-con-el-viento\/","name":"raxxa Premium-Tasse: Poemas de hojas y corazones que vuelan con el viento - raxxa","isPartOf":{"@id":"https:\/\/www.raxxa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-tasse-poemas-de-hojas-y-corazones-que-vuelan-con-el-viento\/#primaryimage"},"image":{"@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-tasse-poemas-de-hojas-y-corazones-que-vuelan-con-el-viento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2025\/08\/raxxa-Tasse-346-19860-143-Toc-de-Groc-Poemas-de-hojas-y-corazones-que-vuelan-con-el-viento-1-scaled.png","datePublished":"2025-05-10T16:22:38+00:00","dateModified":"2025-05-10T16:22:39+00:00","breadcrumb":{"@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-tasse-poemas-de-hojas-y-corazones-que-vuelan-con-el-viento\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.raxxa.com\/shop\/raxxa-premium-tasse-poemas-de-hojas-y-corazones-que-vuelan-con-el-viento\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-tasse-poemas-de-hojas-y-corazones-que-vuelan-con-el-viento\/#primaryimage","url":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2025\/08\/raxxa-Tasse-346-19860-143-Toc-de-Groc-Poemas-de-hojas-y-corazones-que-vuelan-con-el-viento-1-scaled.png","contentUrl":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2025\/08\/raxxa-Tasse-346-19860-143-Toc-de-Groc-Poemas-de-hojas-y-corazones-que-vuelan-con-el-viento-1-scaled.png","width":2560,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/www.raxxa.com\/shop\/raxxa-premium-tasse-poemas-de-hojas-y-corazones-que-vuelan-con-el-viento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.raxxa.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.raxxa.com\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"raxxa Premium-Tasse: Poemas de hojas y corazones que vuelan con el viento"}]},{"@type":"WebSite","@id":"https:\/\/www.raxxa.com\/#website","url":"https:\/\/www.raxxa.com\/","name":"raxxa","description":"Unique individual products from our designers","publisher":{"@id":"https:\/\/www.raxxa.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.raxxa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.raxxa.com\/#organization","name":"raxxa","url":"https:\/\/www.raxxa.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.raxxa.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2022\/07\/logo_v2.png","contentUrl":"https:\/\/www.raxxa.com\/wp-content\/uploads\/2022\/07\/logo_v2.png","width":380,"height":382,"caption":"raxxa"},"image":{"@id":"https:\/\/www.raxxa.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/raxxacom"]}]},"product_price_amount":"18.90","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"1-14518-19860-346","product_condition":"new"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.raxxa.com\/en\/wp-json\/wp\/v2\/product\/225689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.raxxa.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.raxxa.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.raxxa.com\/en\/wp-json\/wp\/v2\/comments?post=225689"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.raxxa.com\/en\/wp-json\/wp\/v2\/media\/238170"}],"wp:attachment":[{"href":"https:\/\/www.raxxa.com\/en\/wp-json\/wp\/v2\/media?parent=225689"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.raxxa.com\/en\/wp-json\/wp\/v2\/product_brand?post=225689"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.raxxa.com\/en\/wp-json\/wp\/v2\/product_cat?post=225689"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.raxxa.com\/en\/wp-json\/wp\/v2\/product_tag?post=225689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}